{"id":2966,"date":"2022-08-23T17:48:12","date_gmt":"2022-08-23T15:48:12","guid":{"rendered":"https:\/\/www.frutas-biobena.com\/cosecha-ecologica-2022-frutas-tropicales\/"},"modified":"2022-08-23T21:53:19","modified_gmt":"2022-08-23T19:53:19","slug":"cosecha-ecologica-2022-frutas-tropicales","status":"publish","type":"post","link":"https:\/\/www.frutas-biobena.com\/es\/cosecha-ecologica-2022-frutas-tropicales\/","title":{"rendered":"COSECHA ECOL\u00d3GICA 2022 FRUTAS TROPICALES"},"content":{"rendered":"<h2><strong>FRUTAS TROPICALES DE ANDALUC\u00cdA<\/strong><\/h2>\n<h2><strong>Mangos ecol\u00f3gicos de la variedad Osteen directo del \u00e1rbol de mango ecol\u00f3gico a tu casa, una de las mejores frutas tropicales<br \/>\n<\/strong><\/h2>\n<h2>Un a\u00f1o m\u00e1s queremos invitarte a visitar nuestra nueva tienda online desde principios de septiembre. <b>ATENCI\u00d3N:<\/b> A partir de septiembre encontrar\u00e1 aqu\u00ed nuestra tienda: <b><br \/>\n<a class=\"moz-txt-link-freetext\" href=\"https:\/\/www.frutas-biobena.com\/\">https:\/\/www.frutas-biobena.com\/<\/a><br \/>\n<\/b><br \/>\nLos clientes que ya ten\u00edan una cuenta de cliente en nuestra antigua tienda online conservan sus datos de acceso y pueden entrar en nuestra nueva tienda online sin problemas.<\/h2>\n<h2>Nos complace poder ofrecerles de nuevo este a\u00f1o nuestras excepcionales frutas tropicales. Empezamos a vender nuestro <a href=\"https:\/\/www.frutas-biobena.com\/produkt\/bio-mango-osteen\/\">Mango Osteen ecol\u00f3gico<\/a> en septiembre.<\/h2>\n<h2>Nuestros mangos y otras frutas tropicales han sido mimados abundantemente por el sol hasta ahora y ser\u00e1n dulces y jugosos a partir de septiembre. Recogemos la fruta poco antes de enviarla, siempre en el momento \u00f3ptimo de maduraci\u00f3n.<br \/>\nCada fruta es \u00fanica en tama\u00f1o y apariencia. Un kilo de mango contiene entre 1 y 5 frutos.<\/h2>\n<figure id=\"attachment_2963\" aria-describedby=\"caption-attachment-2963\" style=\"width: 500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.frutas-biobena.com\/wp-content\/uploads\/hand-mango-offenCrowdfarming_MANGOS-ARROYO-DE-LA-HUERTA_edu-rosa_044.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2963 size-full\" src=\"https:\/\/www.frutas-biobena.com\/wp-content\/uploads\/hand-mango-offenCrowdfarming_MANGOS-ARROYO-DE-LA-HUERTA_edu-rosa_044.jpg\" alt=\"frutas tropicales\" width=\"500\" height=\"334\" srcset=\"https:\/\/www.frutas-biobena.com\/wp-content\/uploads\/hand-mango-offenCrowdfarming_MANGOS-ARROYO-DE-LA-HUERTA_edu-rosa_044.jpg 500w, https:\/\/www.frutas-biobena.com\/wp-content\/uploads\/hand-mango-offenCrowdfarming_MANGOS-ARROYO-DE-LA-HUERTA_edu-rosa_044-300x200.jpg 300w, https:\/\/www.frutas-biobena.com\/wp-content\/uploads\/hand-mango-offenCrowdfarming_MANGOS-ARROYO-DE-LA-HUERTA_edu-rosa_044-416x278.jpg 416w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><figcaption id=\"caption-attachment-2963\" class=\"wp-caption-text\">Fruta de mango ecol\u00f3gica madura para la cosecha<\/figcaption><\/figure>\n<h3><strong><i>Datos interesantes sobre el mango: <\/i><\/strong><i><br \/>\n<\/i><i> <\/i><i><br \/>\n<\/i><i> Los frutos del mango tienen una c\u00e1scara blanquecina de aspecto pulverulento llamada \u00abpruina\u00bb (\u00abbloom\u00bb en ingl\u00e9s). Puede que lo conozcas por otras frutas como los ar\u00e1ndanos, las uvas, las ciruelas, etc. La funci\u00f3n de la pruina es sencilla: protege la fruta de las influencias externas, como las quemaduras del sol, las plagas, la humedad y los hongos, etc. En nuestro caso, la pruina nos ayuda a conservar la fruta en tr\u00e1nsito y durante la posmaduraci\u00f3n en casa, de ah\u00ed nuestra petici\u00f3n: No lave la fruta del mango cuando la reciba. Es muy recomendable dejarlos con esta capa salvavidas hasta que los frutos est\u00e9n completamente maduros.<\/i><i><br \/>\n<\/i><i> <\/i><i><br \/>\n<\/i><i> El mango contiene un l\u00edquido blanquecino en el ped\u00fanculo de la fruta, tambi\u00e9n llamado l\u00e1tex, que puede provocar irritaci\u00f3n de la piel e incluso dermatitis. Por lo tanto, hay que tener mucho cuidado durante la recolecci\u00f3n, tanto y sobre todo para los cosechadores, pero tambi\u00e9n para evitar posibles manchas en la fruta. Sin embargo, el l\u00e1tex no cambia el sabor ni la textura de los mangos. No obstante, en la recolecci\u00f3n tenemos mucho cuidado de que nuestros frutos no presenten manchas de l\u00e1tex.<\/i><i><\/i><\/h3>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #ff0000;\">OFERTA MANGO ORG\u00c1NICO OSTEEN 2022<\/span><\/h2>\n<h3>\u00bfDesea comprar<strong> m\u00e1s de una caja de<\/strong> BIO MANGO OSTEEN durante toda la temporada de mango ecol\u00f3gico de 2022?<\/h3>\n<h3>Entonces env\u00edenos un correo electr\u00f3nico antes <strong>del 31.08.2022 a<\/strong> <a class=\"moz-txt-link-abbreviated moz-txt-link-freetext\" href=\"mailto:bestellung@frutas-biobena.com\">bestellung@frutas-biobena.com<\/a>. Puede ahorrar aproximadamente un 10% en cada caja!!!!<\/h3>\n<p><b>Algunos datos previos para la reserva con un 10% de descuento:<\/b><\/p>\n<p><strong>1. \u00bfQu\u00e9 cajas BIO MANGO puedes elegir?<\/strong><\/p>\n<p><strong>5 kg por 30,66 euros<\/strong> * en lugar de 33,95 euros* en la tienda online (env\u00edo dentro de Alemania) o<\/p>\n<p><strong>10 kg por 49,38 euros*<\/strong> en lugar de 54,53 euros* en la tienda online (env\u00edo dentro de Alemania)<\/p>\n<p>* Para Austria, B\u00e9lgica, Pa\u00edses Bajos, Luxemburgo, Italia, Francia consultar precios.<\/p>\n<p><b>2.<\/b> Aqu\u00ed est\u00e1n nuestras fechas de <strong>env\u00edo<\/strong> para la temporada de ventas de BIO MANGO OSTEEN:<\/p>\n<p>\u00a1Elija sus fechas de env\u00edo deseadas!<\/p>\n<p>Lun 05 \/ Jue 08.09.<br \/>\nLun 12 \/ Jue 15.09.<br \/>\nLun 19 \/ Jue 22.09.<br \/>\nLunes 26\/jueves 29.09.<br \/>\nLun 03 \/ Jue 06.10<br \/>\nLunes 10\/jueves 13 de octubre<br \/>\nLunes 17\/jueves 20 de octubre<br \/>\nLunes 24\/jueves 27.10.*<\/p>\n<p>* Si no es posible despachar la cantidad de mangos pedidos el \u00faltimo d\u00eda de env\u00edo debido a las condiciones meteorol\u00f3gicas o por otros motivos, ofrecemos sustituir la variedad Osteen por la variedad Keitt.<\/p>\n<p>Enviamos con <a href=\"https:\/\/www.gls-spain.es\" target=\"_blank\" rel=\"noopener\">GLS.<\/a> Plazos de entrega: Alemania, Francia 2-4 d\u00edas laborables, Austria, Italia, B\u00e9lgica, Luxemburgo, Pa\u00edses Bajos 3-5 d\u00edas laborables<\/p>\n<p><strong>3. \u00a1Por favor ingrese una direcci\u00f3n de entrega!<\/strong><\/p>\n<p><strong>4. PAGO: Pago por adelantado mediante transferencia bancaria (recibir\u00e1 los datos bancarios con la confirmaci\u00f3n* del pedido).<\/strong><\/p>\n<p>Con saludos cordiales<\/p>\n<p>El equipo de Frutas Biobena<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FRUTAS TROPICALES DE ANDALUC\u00cdA Mangos ecol\u00f3gicos de la variedad Osteen directo del \u00e1rbol de mango ecol\u00f3gico a tu casa, una de las mejores frutas tropicales Un a\u00f1o m\u00e1s queremos invitarte a visitar nuestra nueva tienda online desde principios de septiembre. ATENCI\u00d3N: A partir de septiembre encontrar\u00e1 aqu\u00ed nuestra tienda: https:\/\/www.frutas-biobena.com\/ Los clientes que ya ten\u00edan [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-2966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/posts\/2966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/comments?post=2966"}],"version-history":[{"count":4,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/posts\/2966\/revisions"}],"predecessor-version":[{"id":2971,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/posts\/2966\/revisions\/2971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/media\/2946"}],"wp:attachment":[{"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/media?parent=2966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/categories?post=2966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.frutas-biobena.com\/es\/wp-json\/wp\/v2\/tags?post=2966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}